{"id":14777,"date":"2020-04-03T10:37:56","date_gmt":"2020-04-03T08:37:56","guid":{"rendered":"https:\/\/almanimal.com\/?p=14777"},"modified":"2020-05-02T18:35:28","modified_gmt":"2020-05-02T16:35:28","slug":"avoir-un-rat-a-la-maison","status":"publish","type":"post","link":"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/","title":{"rendered":"Garder un rat dans la maison : tout ce qu'il faut savoir avant de le faire"},"content":{"rendered":"<p>Saviez-vous qu&#039;il est de plus en plus fr\u00e9quent de se retrouver <strong>les personnes qui gardent des rats comme animaux de compagnie<\/strong>Malgr\u00e9 leur mauvaise r\u00e9putation, les rats sont amicaux. <a href=\"https:\/\/almanimal.com\/fr\/petits-mammiferes\/avoir-un-ecureuil-a-la-maison\/\">rongeurs<\/a>Nous vous proposons de briser les pr\u00e9jug\u00e9s sociaux sur cet animal en en apprenant davantage sur ses habitudes, son alimentation et sa gentillesse. Cela pourrait peut-\u00eatre vous faire changer d&#039;avis. <strong>ce que c&#039;est que d&#039;avoir un rat dans sa maison. <\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vous avez un rat \u00e0 la maison ?<\/h2>\n\n\n\n<p>Les rats sont des animaux <strong>mammif\u00e8res, omnivores et rongeurs<\/strong>Leur corps est couvert de poils, de longueur variable selon la race \u00e0 laquelle ils appartiennent, et avec des nuances de gris.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"680\" src=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-dos-1000x680.jpg\" alt=\"Aimeriez-vous avoir un rat comme animal de compagnie ?\" class=\"wp-image-14783\" srcset=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-dos-1000x680.jpg 1000w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-dos-300x204.jpg 300w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-dos-768x523.jpg 768w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-dos.jpg 1536w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<p>Son corps est petit et allong\u00e9, soutenu par quatre pattes courtes et tr\u00e8s agiles, termin\u00e9es par des orteils reli\u00e9s par de petites membranes, et une longue queue. Celle-ci varie \u00e9galement selon l&#039;esp\u00e8ce \u00e0 laquelle il appartient. <strong>sa longue queue sert de r\u00e9gulateur de sa temp\u00e9rature corporelle<\/strong>C&#039;est curieux, n&#039;est-ce pas ? <\/p>\n\n\n\n<p>Il existe diff\u00e9rentes races de ce type de rongeur, dont certaines n\u00e9cessitent des soins plus sp\u00e9cifiques. Toutes sont<strong> animaux tr\u00e8s intelligents<\/strong>C&#039;est pr\u00e9cis\u00e9ment gr\u00e2ce \u00e0 cette intelligence qu&#039;il est conseill\u00e9 d&#039;\u00e9duquer ce chien \u00e0 certains comportements que d&#039;autres animaux auront du mal \u00e0 apprendre. Et oui, <strong>Les rats ont de la m\u00e9moire, et une tr\u00e8s bonne.<\/strong>. <\/p>\n\n\n\n<p>Ce sont des animaux<strong> tr\u00e8s sociable<\/strong>, un rat ne vit jamais isol\u00e9 du groupe \u00e0 l&#039;\u00e9tat sauvage, car ils vivent en communaut\u00e9, nous ne devons donc pas les isoler de leur sexe lorsque nous les adoptons comme animaux de compagnie \u00e0 avoir \u00e0 la maison. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pourquoi est-ce une bonne id\u00e9e d\u2019avoir un rat comme animal de compagnie ?<\/h3>\n\n\n\n<p>Sa mauvaise r\u00e9putation est due au fait qu&#039;il a \u00e9t\u00e9 prouv\u00e9 qu&#039;au XIVe si\u00e8cle, c&#039;\u00e9tait le <strong>responsable ultime de la transmission de la peste bubonique,<\/strong> l&#039;un des premiers <a href=\"https:\/\/almanimal.com\/fr\/sante-du-chien\/votre-chien-peut-etre-en-mesure-de-vous-infecter-avec-le-coronavirus-covid-19\/\">pand\u00e9mies <\/a>Partout dans le monde. De tout temps, on a consid\u00e9r\u00e9 qu&#039;il s&#039;agissait d&#039;un rongeur \u00e0 \u00e9loigner. Mais et si nous avions tort\u00a0?<strong> Avoir un rat \u00e0 la maison ne pr\u00e9sente pas de plus grand risque pour notre sant\u00e9 qu\u2019avoir un autre animal de compagnie. <\/strong>Tous les animaux sont des vecteurs potentiels de maladies, tout comme les humains eux-m\u00eames.  <\/p>\n\n\n\n<p>En fait, le rat est un animal de compagnie plut\u00f4t b\u00e9n\u00e9fique et <strong>un partenaire de vie magnifique. <\/strong>Si vous choisissez d&#039;en acheter un <strong>rat de compagnie <\/strong>vous devez garder \u00e0 l&#039;esprit que <strong>C&#039;est un animal tr\u00e8s sociable<\/strong>Il va donc devoir vivre en groupe. Donc oui, si vous voulez avoir un rat chez vous, je suis d\u00e9sol\u00e9, mais <strong>Pour leur bien-\u00eatre, vous devrez pr\u00e9voir d&#039;en adopter deux, de pr\u00e9f\u00e9rence deux femelles.<\/strong>, qui sont moins territoriaux.<\/p>\n\n\n\n<p>Avant d&#039;avoir un animal de compagnie chez vous, un rat ou tout autre animal, vous devez prendre en compte ce qu&#039;implique une s\u00e9rie de choses.<strong> soins et d\u00e9vouement <\/strong>que vous ne pourrez peut-\u00eatre pas offrir. R\u00e9fl\u00e9chissez-y \u00e0 deux fois avant d&#039;abandonner. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"852\" height=\"480\" src=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-razas.jpg\" alt=\"nourriture des rats domestiques\" class=\"wp-image-14782\" srcset=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-razas.jpg 852w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-razas-300x169.jpg 300w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-razas-768x433.jpg 768w\" sizes=\"(max-width: 852px) 100vw, 852px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Soins n\u00e9cessaires pour avoir un rat \u00e0 la maison comme animal de compagnie<\/h2>\n\n\n\n<p>Vous ne le direz peut-\u00eatre pas au premier abord, mais<strong> Les rats sont des animaux de compagnie tr\u00e8s affectueux<\/strong>Si vous parvenez \u00e0 surmonter les pr\u00e9jug\u00e9s concernant le fait d&#039;avoir un rat \u00e0 la maison comme animal de compagnie, vous d\u00e9couvrirez <strong>un animal magnifique<\/strong>Mais il faut \u00eatre tr\u00e8s prudent et aimant. Ce sont les <strong>besoins essentiels<\/strong> pour les couvrir afin qu&#039;ils soient heureux et en bonne sant\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La cage, la cl\u00e9 pour prendre soin de votre nouvel animal de compagnie<\/h3>\n\n\n\n<p>Si vous d\u00e9cidez d&#039;acheter ce mignon petit animal, vous devrez lui fournir <strong><a href=\"https:\/\/almanimal.com\/fr\/accessoires-pour-petits-mammiferes\/meilleures-cages-pour-rats\/\">une cage assez grande<\/a>, qui a deux conteneurs<\/strong>, l&#039;un exclusivement pour la nourriture et l&#039;autre pour l&#039;eau, en veillant \u00e0 ce qu&#039;ils soient propres, ainsi qu&#039;un nid pour dormir. <\/p>\n\n\n\n<p>La surface du lit doit \u00eatre g\u00e9n\u00e9reusement recouverte de <strong>copeaux de bois, toujours ceux sp\u00e9cifiquement con\u00e7us pour les rats<\/strong>, ce qui servira de distraction, car ils ont toujours tendance \u00e0 faire des trous. C&#039;est leur passion, que pouvons-nous y faire\u00a0? <\/p>\n\n\n\n<p>Ils doivent \u00e9galement avoir dans leur cage <strong>objets de distraction, tels que des jouets<\/strong> et des ustensiles qui motivent le mouvement et l&#039;activit\u00e9, car en raison de leur m\u00e9tabolisme, ils ont tendance \u00e0 \u00eatre ob\u00e8ses.<\/p>\n\n\n\n<p>La taille id\u00e9ale ? Au moins <strong>0,25 m\u00e8tre carr\u00e9<\/strong>; soyez prudent, car il faut veiller \u00e0 ce que la cage ait un espacement entre les barreaux inf\u00e9rieur \u00e0 un centim\u00e8tre. En bref, il faut que ce soit un <strong>suffisamment d&#039;espace pour couvrir leurs besoins en mati\u00e8re de liti\u00e8re et d&#039;alimentation et avoir de la place pour jouer.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les meilleures offres sur les cages \u00e0 rats<\/h4>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Nourrir un rat de compagnie<\/h3>\n\n\n\n<p>Quant \u00e0 leur r\u00e9gime alimentaire, bien qu\u2019ils soient omnivores, il faut<strong> surveille ta nourriture. <\/strong>\u00c7a doit \u00eatre \u00e7a <strong>vari\u00e9 et complet<\/strong>, en \u00e9vitant les aliments trop \u00e9nerg\u00e9tiques et gras, ainsi que certains agrumes et les aliments en mauvais \u00e9tat ou <strong>les aliments qui produisent des gaz, car ils peuvent vous rendre malade<\/strong>.<\/p>\n\n\n\n<p>Ils existent sur le march\u00e9 <strong>aliments pr\u00e9par\u00e9s sp\u00e9cifiques pour rongeurs<\/strong> qui contiennent tous les nutriments dont ils ont besoin ; ils sont principalement constitu\u00e9s de c\u00e9r\u00e9ales, comme l&#039;avoine et le ma\u00efs, de noix, comme les graines de tournesol et de citrouille, et d&#039;autres petites graines pr\u00e9sentes dans les graines pour oiseaux. <\/p>\n\n\n\n<p>Ce type d&#039;alimentation devrait repr\u00e9senter jusqu&#039;\u00e0 80% de votre apport quotidien, en plus de<strong> prot\u00e9ines fournies par le b\u0153uf et le poulet <\/strong>(la viande doit toujours \u00eatre cuite).<\/p>\n\n\n\n<p>\u00c9quilibrez votre alimentation en lui proposant <strong>fruit<\/strong>, comme les pommes, les bananes ou les cerises, par exemple, mais sans peau ni p\u00e9pins ; <strong>l\u00e9gumes <\/strong>comme les carottes, les blettes ou le chou, mais bien lav\u00e9s ; nous pouvons \u00e9galement inclure des produits laitiers dans leur alimentation comme le yaourt et, bien s\u00fbr, <strong>fromage <\/strong>-oui, ils adorent \u00e7a-, ainsi que <strong>aliments contenant du sucre<\/strong>, comme des cookies.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les meilleures offres de nourriture pour rats domestiques<\/h4>\n\n\n\n\n\n\n<h3 class=\"wp-block-heading\">Le caract\u00e8re des rats domestiques<\/h3>\n\n\n\n<p>Les rats, jusqu&#039;\u00e0 ce qu&#039;ils s&#039;habituent \u00e0 la main de leur propri\u00e9taire, ont tendance \u00e0 \u00eatre insociables et m\u00e9fiants\u00a0; <strong>Leur instinct les pousse \u00e0 vouloir fuir mais ils ne sont jamais agressifs. <\/strong><\/p>\n\n\n\n<p>Pour qu&#039;ils s&#039;habituent \u00e0 leur nouvel habitat et fassent confiance \u00e0 leur propri\u00e9taire, il faut <strong>pers\u00e9v\u00e9rant et ayant beaucoup de patience.<\/strong> Il faut les habituer \u00e0 cela par un contact doux et sans \u00e9lever la voix, en consacrant au moins une heure par jour \u00e0 cette t\u00e2che. <\/p>\n\n\n\n<p>Alors nous pouvons <strong>R\u00e9compensez-la avec un biscuit ou un bonbon, mais n&#039;en faites pas trop.<\/strong> car nous pourrions causer des dommages \u00e0 leur organisme, et nous rendons compte qu&#039;ils le mangent parce que ce sont des animaux qui ont tendance \u00e0 laisser la nourriture stock\u00e9e et empil\u00e9e.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1000\" height=\"832\" src=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-1000x832.jpg\" alt=\"avoir un rat \u00e0 la maison comme animal de compagnie\" class=\"wp-image-14781\" srcset=\"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-1000x832.jpg 1000w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-300x250.jpg 300w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota-768x639.jpg 768w, https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/tener-rata-en-casa-mascota.jpg 1024w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Autres soins et pr\u00e9cautions que nous devrions prendre avec eux<\/h3>\n\n\n\n<p><strong>Nous veillerons \u00e0 ce qu&#039;il ne soit pas mouill\u00e9<\/strong>, sauf prescription d&#039;un v\u00e9t\u00e9rinaire, car ce sont des animaux avec <strong>tendance \u00e0 se refroidir et peut m\u00eame mourir si nous ne le remarquons pas<\/strong>.<\/p>\n\n\n\n<p>Nous surveillerons son carnet de vaccination et sa vermifugation, ainsi que son comportement, car elle pourrait \u00eatre malade. Si nous la voyons se gratter fr\u00e9quemment, si elle ne joue pas ou ne bouge pas rapidement\u2026<strong>nous devons \u00eatre vigilants.<\/strong><\/p>\n\n\n\n<p>Nous pouvons \u00e9galement d\u00e9tecter des desquamations ou des rougeurs de la peau, des bosses et des inflammations au toucher. <strong>Ce sont de petits animaux qui d\u00e9veloppent assez fr\u00e9quemment un cancer.<\/strong>Si nous constatons une anomalie, nous devons consulter le v\u00e9t\u00e9rinaire.<\/p>\n\n\n\n<p>Avons-nous r\u00e9ussi \u00e0 vous convaincre d&#039;adopter un rat comme animal de compagnie\u00a0? En avez-vous un\u00a0? Racontez-nous votre exp\u00e9rience\u00a0!<\/p>","protected":false},"excerpt":{"rendered":"<p>Saviez-vous que de plus en plus de gens adoptent des rats comme animaux de compagnie\u00a0? Malgr\u00e9 leur mauvaise r\u00e9putation, les rats sont en r\u00e9alit\u00e9 des rongeurs plut\u00f4t attachants. Nous vous invitons \u00e0 d\u00e9passer les pr\u00e9jug\u00e9s qui les entourent en d\u00e9couvrant leurs habitudes, leur alimentation et leur nature douce. Qui sait, votre regard sur eux changera peut-\u00eatre\u2026 <a title=\"Garder un rat dans la maison : tout ce qu&#039;il faut savoir avant de le faire\" class=\"read-more\" href=\"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/\" aria-label=\"Apprenez-en davantage sur la pr\u00e9sence d\u2019un rat chez vous\u00a0: tout ce que vous devez savoir avant d\u2019en adopter un.\">Lire la suite<\/a><\/p>","protected":false},"author":20,"featured_media":14785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1433],"tags":[1873,1872,1869,1874,1870,1541],"class_list":["post-14777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidados-pequenos-mamiferos","tag-accesorios-para-roedores","tag-alimentacion-roedores","tag-cuidados-pequenos-mamiferos","tag-cuidados-roedores","tag-ratas-como-mascota","tag-roedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tener una rata en casa: todo lo que debes de saber antes de hacerlo<\/title>\n<meta name=\"description\" content=\"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tener una rata en casa: todo lo que debes de saber antes de hacerlo\" \/>\n<meta property=\"og:description\" content=\"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/\" \/>\n<meta property=\"og:site_name\" content=\"Almanimal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Lugarnia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-03T08:37:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-02T16:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Fresneda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lugarnia_\" \/>\n<meta name=\"twitter:site\" content=\"@lugarnia_\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Fresneda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Fresneda\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/#\\\/schema\\\/person\\\/6ed186ff065669ae7edab360e747304d\"},\"headline\":\"Tener una rata en casa: todo lo que debes de saber antes de hacerlo\",\"datePublished\":\"2020-04-03T08:37:56+00:00\",\"dateModified\":\"2020-05-02T16:35:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/\"},\"wordCount\":1247,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg\",\"keywords\":[\"accesorios para roedores\",\"alimentaci\u00f3n roedores\",\"cuidados peque\u00f1os mam\u00edferos\",\"cuidados roedores\",\"ratas como mascota\",\"roedores\"],\"articleSection\":[\"Cuidados Peque\u00f1os mam\u00edferos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/\",\"url\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/\",\"name\":\"Tener una rata en casa: todo lo que debes de saber antes de hacerlo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg\",\"datePublished\":\"2020-04-03T08:37:56+00:00\",\"dateModified\":\"2020-05-02T16:35:28+00:00\",\"description\":\"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg\",\"contentUrl\":\"https:\\\/\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Tener una rata en casa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/tener-una-rata-en-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/almanimal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidados Peque\u00f1os mam\u00edferos\",\"item\":\"https:\\\/\\\/almanimal.com\\\/cuidados-pequenos-mamiferos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tener una rata en casa: todo lo que debes de saber antes de hacerlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/#website\",\"url\":\"https:\\\/\\\/almanimal.com\\\/\",\"name\":\"Almanimal\",\"description\":\"Revista de animales donde hablamos sobre perros, gatos, aves, peque\u00f1os mam\u00edferos, acuarios, terrarios y curiosidades del mundo animal.\",\"publisher\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/almanimal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/#organization\",\"name\":\"Almanimal\",\"url\":\"https:\\\/\\\/almanimal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/almanimal_logo-nav-3.png?fit=400%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/almanimal.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/almanimal_logo-nav-3.png?fit=400%2C100&ssl=1\",\"width\":400,\"height\":100,\"caption\":\"Almanimal\"},\"image\":{\"@id\":\"https:\\\/\\\/almanimal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Lugarnia\\\/\",\"https:\\\/\\\/x.com\\\/lugarnia_\",\"https:\\\/\\\/www.instagram.com\\\/lugarnia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/almanimal.com\\\/#\\\/schema\\\/person\\\/6ed186ff065669ae7edab360e747304d\",\"name\":\"Iv\u00e1n Fresneda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g\",\"caption\":\"Iv\u00e1n Fresneda\"},\"url\":\"https:\\\/\\\/almanimal.com\\\/fr\\\/author\\\/ivanfc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tener una rata en casa: todo lo que debes de saber antes de hacerlo","description":"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/","og_locale":"fr_FR","og_type":"article","og_title":"Tener una rata en casa: todo lo que debes de saber antes de hacerlo","og_description":"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.","og_url":"https:\/\/almanimal.com\/fr\/soins-aux-petits-mammiferes\/avoir-un-rat-a-la-maison\/","og_site_name":"Almanimal","article_publisher":"https:\/\/www.facebook.com\/Lugarnia\/","article_published_time":"2020-04-03T08:37:56+00:00","article_modified_time":"2020-05-02T16:35:28+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i2.wp.com\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Iv\u00e1n Fresneda","twitter_card":"summary_large_image","twitter_creator":"@lugarnia_","twitter_site":"@lugarnia_","twitter_misc":{"\u00c9crit par":"Iv\u00e1n Fresneda","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#article","isPartOf":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/"},"author":{"name":"Iv\u00e1n Fresneda","@id":"https:\/\/almanimal.com\/#\/schema\/person\/6ed186ff065669ae7edab360e747304d"},"headline":"Tener una rata en casa: todo lo que debes de saber antes de hacerlo","datePublished":"2020-04-03T08:37:56+00:00","dateModified":"2020-05-02T16:35:28+00:00","mainEntityOfPage":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/"},"wordCount":1247,"commentCount":2,"publisher":{"@id":"https:\/\/almanimal.com\/#organization"},"image":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg","keywords":["accesorios para roedores","alimentaci\u00f3n roedores","cuidados peque\u00f1os mam\u00edferos","cuidados roedores","ratas como mascota","roedores"],"articleSection":["Cuidados Peque\u00f1os mam\u00edferos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/","url":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/","name":"Tener una rata en casa: todo lo que debes de saber antes de hacerlo","isPartOf":{"@id":"https:\/\/almanimal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#primaryimage"},"image":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg","datePublished":"2020-04-03T08:37:56+00:00","dateModified":"2020-05-02T16:35:28+00:00","description":"\u00bfSab\u00edas que cada vez es m\u00e1s habitual encontrarnos personas que tienen ratas como mascotas? Conocerlas cambiar\u00e1 tu idea sobre c\u00f3mo es tener una rata en casa.","breadcrumb":{"@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#primaryimage","url":"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg","contentUrl":"https:\/\/almanimal.com\/wp-content\/uploads\/2020\/04\/consejos-tener-rata-en-casa-mascota-e1585821336879.jpg","width":1200,"height":800,"caption":"Tener una rata en casa"},{"@type":"BreadcrumbList","@id":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/tener-una-rata-en-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/almanimal.com\/"},{"@type":"ListItem","position":2,"name":"Cuidados Peque\u00f1os mam\u00edferos","item":"https:\/\/almanimal.com\/cuidados-pequenos-mamiferos\/"},{"@type":"ListItem","position":3,"name":"Tener una rata en casa: todo lo que debes de saber antes de hacerlo"}]},{"@type":"WebSite","@id":"https:\/\/almanimal.com\/#website","url":"https:\/\/almanimal.com\/","name":"Almanimal","description":"Revista de animales donde hablamos sobre perros, gatos, aves, peque\u00f1os mam\u00edferos, acuarios, terrarios y curiosidades del mundo animal.","publisher":{"@id":"https:\/\/almanimal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/almanimal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/almanimal.com\/#organization","name":"Almanimal","url":"https:\/\/almanimal.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/almanimal.com\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/almanimal.com\/wp-content\/uploads\/2019\/10\/almanimal_logo-nav-3.png?fit=400%2C100&ssl=1","contentUrl":"https:\/\/i2.wp.com\/almanimal.com\/wp-content\/uploads\/2019\/10\/almanimal_logo-nav-3.png?fit=400%2C100&ssl=1","width":400,"height":100,"caption":"Almanimal"},"image":{"@id":"https:\/\/almanimal.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lugarnia\/","https:\/\/x.com\/lugarnia_","https:\/\/www.instagram.com\/lugarnia\/"]},{"@type":"Person","@id":"https:\/\/almanimal.com\/#\/schema\/person\/6ed186ff065669ae7edab360e747304d","name":"Iv\u00e1n Fresneda","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/679537483addce5c0f78eeeee0668dd50e7ac9271515218de2d0dc202748741c?s=96&d=mm&r=g","caption":"Iv\u00e1n Fresneda"},"url":"https:\/\/almanimal.com\/fr\/author\/ivanfc\/"}]}},"_links":{"self":[{"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/posts\/14777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/comments?post=14777"}],"version-history":[{"count":1,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/posts\/14777\/revisions"}],"predecessor-version":[{"id":15199,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/posts\/14777\/revisions\/15199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/media\/14785"}],"wp:attachment":[{"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/media?parent=14777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/categories?post=14777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/almanimal.com\/fr\/wp-json\/wp\/v2\/tags?post=14777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}